{"id":16914,"date":"2025-03-31T08:17:47","date_gmt":"2025-03-31T08:17:47","guid":{"rendered":"https:\/\/www.vtmarketseu.com\/it\/?p=16914"},"modified":"2025-03-31T08:20:36","modified_gmt":"2025-03-31T08:20:36","slug":"v2025033101","status":"publish","type":"post","link":"https:\/\/www.vtmarketseu.com\/it\/dividend\/v2025033101\/","title":{"rendered":"Avviso di Regolazione dei Dividendi &#8211; Mar 31 ,2025"},"content":{"rendered":"\n<p>\n    Gentile Cliente,\n<\/p>\n<p>\n    Si prega di notare che i dividendi dei seguenti prodotti verranno regolati di conseguenza. I dividendi sugli indici verranno eseguiti separatamente tramite un estratto conto direttamente sul tuo conto di trading e il commento seguir\u00e0 il seguente formato: \u201cDiv &#038; Nome del Prodotto &#038; Volume Netto\u201d.\n<\/p>\n<p>\n    Si prega di consultare la tabella sottostante per maggiori dettagli:\n<\/p>\n<p>\n<img decoding=\"async\" src=\"\/email_img\/email_it2025033101.jpg\" alt=\"Avviso di Regolazione dei Dividendi\" width=\"660\" height=\"483\">\n<\/p>\n<p>\n    I dati sopra riportati sono solo a scopo di riferimento, si prega di fare riferimento al software MT4\/MT5 per i dati specifici.\n<\/p>\n<p>\n    Per ulteriori informazioni, non esitare a contattare <a href=\"mailto:info@vtmarkets.com\">info@vtmarkets.com.<\/a>\n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gentile Cliente, Si prega di notare che i dividendi dei seguenti prodotti verranno regolati di conseguenza. I dividendi sugli indici verranno eseguiti separatamente tramite un estratto conto direttamente sul tuo conto di trading e il commento seguir\u00e0 il seguente formato: \u201cDiv &#038; Nome del Prodotto &#038; Volume Netto\u201d. Si prega di consultare la tabella sottostante <a href=\"https:\/\/www.vtmarketseu.com\/it\/dividend\/v2025033101\/\" class=\"read-more\">Continue Reading<\/a><\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-16914","post","type-post","status-publish","format-standard","hentry","category-dividend"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.vtmarketseu.com\/it\/wp-json\/wp\/v2\/posts\/16914","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vtmarketseu.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vtmarketseu.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vtmarketseu.com\/it\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vtmarketseu.com\/it\/wp-json\/wp\/v2\/comments?post=16914"}],"version-history":[{"count":0,"href":"https:\/\/www.vtmarketseu.com\/it\/wp-json\/wp\/v2\/posts\/16914\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.vtmarketseu.com\/it\/wp-json\/wp\/v2\/media?parent=16914"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vtmarketseu.com\/it\/wp-json\/wp\/v2\/categories?post=16914"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vtmarketseu.com\/it\/wp-json\/wp\/v2\/tags?post=16914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}